{"id":858,"date":"2013-10-25T03:17:05","date_gmt":"2013-10-25T03:17:05","guid":{"rendered":"http:\/\/www.roslinda.com.ar\/blog\/?p=858"},"modified":"2013-10-25T16:41:23","modified_gmt":"2013-10-25T16:41:23","slug":"te-invito-a-tejer","status":"publish","type":"post","link":"http:\/\/www.roslinda.com.ar\/blog\/te-invito-a-tejer\/","title":{"rendered":"\u00a1Te invito a tejer!"},"content":{"rendered":"<p>Tejer porque te gusta, , tejer para para tu familia, tejer para vos, tejer por trabajo, tejer como terapia, tejer para crear, tejer para recordar a un ser querido&#8230;muchas son las causas o los motivos, que nos llevan a iniciar nuestro camino en la maravillosa t\u00e9cnica del tejido a dos agujas y todas y cada una de ellas, son v\u00e1lidas y por dem\u00e1s valiosas para hacerlo!<\/p>\n<p>El tejido tiene historia, tiene valor, tiene ventajas y tiene infinitas posibilidades de creaci\u00f3n. \u00a0<a href=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/P1000457.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-861\" alt=\"P1000457\" src=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/P1000457-225x300.jpg\" width=\"225\" height=\"300\" srcset=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/P1000457-225x300.jpg 225w, http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/P1000457-768x1024.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>El tejido \u00abhace bien\u00bb!<\/p>\n<p>Por eso comparto con uds. este post, que de seguro las animar\u00e1 a \u00a0comenzar ya mismo con esta gran pasi\u00f3n.<\/p>\n<p>Pasi\u00f3n que, de seguro, las acompa\u00f1ar\u00e1 de por vida!<\/p>\n<p>Con mucho cari\u00f1o,<\/p>\n<p>Roslinda<\/p>\n<p><b><i>Un poquito de historia<\/i><\/b><\/p>\n<p>Desde tiempos remotos, las tejedoras han abrigado con sus tejidos artesanales a generaciones enteras.<\/p>\n<p>Especialmente en la antig\u00fcedad cuando todav\u00eda no hab\u00eda la diversidad de textiles como la que hay ahora, la lana era uno de los materiales m\u00e1s preciados y la ropa se hac\u00eda en forma manual, en ese entonces los tejidos eran el principal recurso para los tiempos de fr\u00edo.<\/p>\n<p>Tejer es una labor que tiene tantos a\u00f1os casi como la humanidad misma.<\/p>\n<p>No podemos olvidar a tejedoras famosas como Pen\u00e9lope de la obra de Homero \u201cLa Odisea\u201d donde espera a su esposo, el famoso Ulises de Troya tejiendo pacientemente hasta el d\u00eda de su llegada.<\/p>\n<p>Si bien este registro literario es un documento de la actividad de la \u00e9poca, lo cierto es que los primeros tejidos se encontraron en Egipto y luego se hallaron en Grecia y Roma.<\/p>\n<p>M\u00e1s tarde, durante la Edad Media se extendi\u00f3 en Europa el uso de gorros tejidos, bonetes y medias que eran indispensables del atuendo de aquella \u00e9poca.<\/p>\n<p><a href=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/001.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-868 alignright\" alt=\"001\" src=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/001-117x300.jpg\" width=\"117\" height=\"300\" \/><\/a><\/p>\n<p>Con la revoluci\u00f3n industrial en Inglaterra, el tejido manual cedi\u00f3 terreno a nuevas l\u00edneas industriales menos originales pero m\u00e1s masivas que ven\u00edan para cubrir la necesidad de poblaciones en crecimiento.<\/p>\n<p>El tejido a mano conserv\u00f3 su lugar y valor como una prenda artesanal y \u00fanica.<\/p>\n<p>Hoy los tejidos son muy valorados y est\u00e1n presentes en los guardarropas de todos tanto en sweaters como en m\u00faltiples accesorios.<\/p>\n<p><b>La era DIY o \u201chacelo vos misma\u201d<\/b><\/p>\n<p>El tejido tiene un valor muy especial, es una de las labores artesanales que nos quedan, donde las manos humanas y las agujas van construyendo una trama, cada punto nos recuerda que en este trabajo hay una herencia cultural legendaria, una tradici\u00f3n de nuestras abuelas\u00a0 y madres.<\/p>\n<p>Los tejidos llevan arte y el enorme valor que representa el trabajo de hacerlo con las propias manos.<\/p>\n<p>Actualmente, hay un redescubrimiento del\u00a0 \u201chacelo vos misma\u201d o \u201chazlo t\u00fa misma\u201d, m\u00e1s conocido en ingl\u00e9s como Do it yourself (DIY) y se trata de revalorar el trabajo manual y la propia creatividad.<\/p>\n<p>Adem\u00e1s, tejer es una actividad terap\u00e9utica y te encantar\u00e1 ver que tus obras visten a tu <a href=\"http:\/\/www.ala.com.ar\/productos\/nuevo-ala-liquido\/\">familia<\/a>.<\/p>\n<p>\u00a1Te invito a aprender a tejer a dos agujas!<\/p>\n<p><b>Ideas de tejidos a dos agujas para toda la familia<\/b><\/p>\n<p>M\u00e1s de 15 ideas de tejidos para ni\u00f1os, para vos, tu familia o para hacer un regalo con un sello muy personal:<\/p>\n<p><b>1 <\/b>Abrigos como sacos y sweaters \u00a0<a href=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/DSC01814.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-862\" alt=\"DSC01814\" src=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/DSC01814-300x206.jpg\" width=\"300\" height=\"206\" srcset=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/DSC01814-300x206.jpg 300w, http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/DSC01814-1024x703.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><b>2 <\/b>Accesorios como flores o figuras de animales para usar como prendedor<\/p>\n<p><b>3 <\/b>Bufandas<\/p>\n<p><b>4<\/b> Carteras<\/p>\n<p><b>5 <\/b>Cuellitos para ni\u00f1os y para adultos<\/p>\n<p><b>6 <\/b>Chalecos<\/p>\n<p><b>7 <\/b>Guantes<\/p>\n<p><b>8<\/b> Gorros<\/p>\n<p><b>9 <\/b>Escarpines \u00a0<a href=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/20130616_120757.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-871\" alt=\"20130616_120757\" src=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/20130616_120757-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/20130616_120757-300x225.jpg 300w, http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/20130616_120757-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><b>10 <\/b>Medias<\/p>\n<p><b>11<\/b> Pantuflas<\/p>\n<p><b>12<\/b> Polainas<\/p>\n<p><b>13<\/b> Polleras<\/p>\n<p><b>14 <\/b>Vestidos<\/p>\n<p><b>15<\/b> Vinchas<\/p>\n<p><b>16 <\/b>Estuches tipo sobre y bolsitas<\/p>\n<p><b>17 <\/b>Y para tus mascotas tambi\u00e9n: \u00a1chalecos para perros y gatos!<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/DSC01967.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-873 aligncenter\" alt=\"DSC01967\" src=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/DSC01967-261x300.jpg\" width=\"261\" height=\"300\" srcset=\"http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/DSC01967-261x300.jpg 261w, http:\/\/www.roslinda.com.ar\/blog\/wp-content\/uploads\/2013\/10\/DSC01967.jpg 859w\" sizes=\"auto, (max-width: 261px) 100vw, 261px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfTen\u00e9s preguntas sobre tejidos a dos agujas? \u00a1Escribime!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tejer porque te gusta, , tejer para para tu familia, tejer para vos, tejer por trabajo, tejer como terapia, tejer para crear, tejer para recordar a un ser querido&#8230;muchas son las causas o los motivos, que nos llevan a iniciar nuestro camino en la maravillosa t\u00e9cnica del tejido a dos agujas y todas y cada una de ellas, son v\u00e1lidas y por dem\u00e1s valiosas para hacerlo! El tejido tiene historia, tiene valor, tiene ventajas y tiene infinitas posibilidades de creaci\u00f3n. \u00a0 El tejido \u00abhace bien\u00bb! Por eso comparto con uds. este post, que de seguro las animar\u00e1 a \u00a0comenzar ya mismo con esta gran pasi\u00f3n. Pasi\u00f3n que, de seguro, las acompa\u00f1ar\u00e1 de por vida! Con mucho cari\u00f1o, Roslinda Un poquito de historia Desde tiempos remotos, las tejedoras han abrigado con sus tejidos artesanales a generaciones enteras. Especialmente en la antig\u00fcedad cuando todav\u00eda no hab\u00eda la diversidad de textiles como la que hay ahora, la lana era uno de los materiales m\u00e1s preciados y la ropa se hac\u00eda en forma manual, en ese entonces los tejidos eran el principal recurso para los tiempos de fr\u00edo. Tejer es una labor que tiene tantos a\u00f1os casi como la humanidad misma. No podemos olvidar a tejedoras famosas como Pen\u00e9lope de la obra de Homero \u201cLa Odisea\u201d donde espera a su esposo, el famoso Ulises de Troya tejiendo pacientemente hasta el d\u00eda de su llegada. Si bien este registro literario es un documento de la actividad de la \u00e9poca, lo cierto es que los primeros tejidos se encontraron en Egipto y luego se hallaron en Grecia y Roma. M\u00e1s tarde, durante la Edad Media se extendi\u00f3 en Europa el uso de gorros tejidos, bonetes y medias que eran indispensables del atuendo de aquella \u00e9poca. Con la revoluci\u00f3n industrial en Inglaterra, el tejido manual cedi\u00f3 terreno a nuevas l\u00edneas industriales menos originales pero m\u00e1s masivas que ven\u00edan para cubrir la necesidad de poblaciones en crecimiento. El tejido a mano conserv\u00f3 su lugar y valor como una prenda artesanal y \u00fanica. Hoy los tejidos son muy valorados y est\u00e1n presentes en los guardarropas de todos tanto en sweaters como en m\u00faltiples accesorios. La era DIY o \u201chacelo vos misma\u201d El tejido tiene un valor muy especial, es una de las labores artesanales que nos quedan, donde las manos humanas y las agujas van construyendo una trama, cada punto nos recuerda que en este trabajo hay una herencia cultural legendaria, una tradici\u00f3n de nuestras abuelas\u00a0 y madres. Los tejidos llevan arte y el enorme valor que representa el trabajo de hacerlo con las propias manos. Actualmente, hay un redescubrimiento del\u00a0 \u201chacelo vos misma\u201d o \u201chazlo t\u00fa misma\u201d, m\u00e1s conocido en ingl\u00e9s como Do it yourself (DIY) y se trata de revalorar el trabajo manual y la propia creatividad. Adem\u00e1s, tejer es una actividad terap\u00e9utica y te encantar\u00e1 ver que tus obras visten a tu familia. \u00a1Te invito a aprender a tejer a dos agujas! Ideas de tejidos a dos agujas para toda la familia M\u00e1s de 15 ideas de tejidos para ni\u00f1os, para vos, tu familia o para hacer un regalo con un sello muy personal: 1 Abrigos como sacos y sweaters \u00a0 2 Accesorios como flores o figuras de animales para usar como prendedor 3 Bufandas 4 Carteras 5 Cuellitos para ni\u00f1os y para adultos 6 Chalecos 7 Guantes 8 Gorros 9 Escarpines \u00a0 10 Medias 11 Pantuflas 12 Polainas 13 Polleras 14 Vestidos 15 Vinchas 16 Estuches tipo sobre y bolsitas 17 Y para tus mascotas tambi\u00e9n: \u00a1chalecos para perros y gatos! &nbsp; &nbsp; \u00bfTen\u00e9s preguntas sobre tejidos a dos agujas? \u00a1Escribime!<\/p>\n","protected":false},"author":1,"featured_media":860,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[16,9],"tags":[],"class_list":["post-858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-invitaciones","category-reflexiones"],"_links":{"self":[{"href":"http:\/\/www.roslinda.com.ar\/blog\/wp-json\/wp\/v2\/posts\/858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.roslinda.com.ar\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.roslinda.com.ar\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.roslinda.com.ar\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.roslinda.com.ar\/blog\/wp-json\/wp\/v2\/comments?post=858"}],"version-history":[{"count":10,"href":"http:\/\/www.roslinda.com.ar\/blog\/wp-json\/wp\/v2\/posts\/858\/revisions"}],"predecessor-version":[{"id":876,"href":"http:\/\/www.roslinda.com.ar\/blog\/wp-json\/wp\/v2\/posts\/858\/revisions\/876"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.roslinda.com.ar\/blog\/wp-json\/wp\/v2\/media\/860"}],"wp:attachment":[{"href":"http:\/\/www.roslinda.com.ar\/blog\/wp-json\/wp\/v2\/media?parent=858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.roslinda.com.ar\/blog\/wp-json\/wp\/v2\/categories?post=858"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.roslinda.com.ar\/blog\/wp-json\/wp\/v2\/tags?post=858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}